{"id":37244,"date":"2022-08-04T07:25:51","date_gmt":"2022-08-04T07:25:51","guid":{"rendered":"https:\/\/iconico.es\/catalogue\/faucets\/basin-faucets\/basin-faucets-collection-a\/"},"modified":"2022-09-22T08:53:51","modified_gmt":"2022-09-22T08:53:51","slug":"collection-a-basin-faucets","status":"publish","type":"page","link":"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/","title":{"rendered":"Collection A basin faucets"},"content":{"rendered":"[vc_row et_column_align=&#8221;align-center&#8221; css=&#8221;.vc_custom_1644854299335{margin-top: 3% !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]\n<h3 style=\"text-align: center;\">Circles and cylinders are the essence of Collection A design. This basin faucets collection has a variety of models of different heights, spout lengths, installation possibilities, \u2014 wall-mounted or on countertop\u2014, mixer typologies to adapt to the functional and aesthetic requirements of each project.<\/h3>\n[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row][vc_row et_column_align=&#8221;align-center&#8221; content_placement=&#8221;top&#8221; css=&#8221;.vc_custom_1638293188128{margin-top: 2% !important;}&#8221; el_class=&#8221;cuadrados-1&#8243;][vc_column]\t<div id=\"et-hovercard-6a572589d5743\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/productos\/griferia-de-lavabo-coleccion-a\/\" target=\"_self\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\">A COLLECTION BASIN FAUCETS<\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\">A COLLECTION BASIN FAUCETS<\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1638293240991{margin-top: 2% !important;}&#8221;][vc_column][vc_btn title=&#8221;VIEW PRODUCTS&#8221; style=&#8221;outline&#8221; shape=&#8221;square&#8221; color=&#8221;black&#8221; align=&#8221;center&#8221; link=&#8221;url:https%3A%2F%2Ficonico.es%2Fproductos%2Fgriferia-de-lavabo-coleccion-a%2F&#8221; css=&#8221;.vc_custom_1663836809315{margin-top: 45px !important;margin-bottom: 45px !important;}&#8221;][\/vc_column][\/vc_row][vc_row et_column_align=&#8221;align-center&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1633429174204{margin-right: 8% !important;margin-left: 8% !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_row_inner et_max_width=&#8221;&#8221; et_column_align=&#8221;align-right&#8221; content_placement=&#8221;top&#8221;][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/6&#8243;][vc_column_text]MIXERS: TYPOLIGIES,<br \/>\nMODELS AND LOCATION[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]\n<p>Two types of mixers make up our catalogue, being able to choose between single lever mixer or double lever mixer valves. Available in two different models, they are designed to be installed both wall-mounted or on countertop, regardless the location of the spout.[\/vc_column_text][\/vc_column][\/vc_row][vc_row et_column_align=&#8221;align-center&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1633429174204{margin-right: 8% !important;margin-left: 8% !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_row_inner et_max_width=&#8221;&#8221; et_column_align=&#8221;align-right&#8221;][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/6&#8243;][vc_column_text]AVAILABLE FINISHES[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]IC\u00d3NICO\u2019s Collection A basin faucets are available in seven finishes: chrome, matt white, matt black, brushed nickel, brushed copper, polished or brushed gold, combinable with any type of covering, product or material.[\/vc_column_text][\/vc_column][\/vc_row][vc_row et_column_align=&#8221;align-center&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1633429174204{margin-right: 8% !important;margin-left: 8% !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_row_inner et_max_width=&#8221;&#8221; et_column_align=&#8221;align-right&#8221;][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/6&#8243;][vc_column_text]FLOW REDUCERS FOR LEED<br \/>\nAND BREEAM CERTIFICATIONS[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]We have technical devices to restrict the flow of water. These allow obtaining the highest scores in BREEAM and LEED certifications, thus promoting water saving and the environmental sustainability of our planet.[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;inspiracion-hover-card&#8221;][vc_column offset=&#8221;vc_hidden-xs&#8221;][vc_separator][vc_column_text css=&#8221;.vc_custom_1642517310755{margin-top: 3% !important;margin-bottom: 3% !important;}&#8221;]\n<h3 style=\"text-align: center;\">Inspiration<\/h3>\n[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589d6746\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/IC3480-20_A-LE23-20_iconico-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589d75e8\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LE23-27_iconico_3-2.jpg\" target=\"_self\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589d814c\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LP21-27_iconico-1-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1638442167127{margin-top: 1rem !important;}&#8221;][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589d8c36\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A2-LE23-20_iconico-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589d9791\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LE22-27_iconico.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1641830953769{margin-top: 1rem !important;}&#8221; el_class=&#8221;scrolll&#8221;][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589da452\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LP22-64_iconico-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589dae82\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/IC212000-20_LR1M-27_A-LE13-27_Sifon-27_14705002305-27_iconico-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589db8be\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/IC212000-20_IC3040-20_A2-LP21-20_LC1M-RAL_iconico-1-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1641830961743{margin-top: 1rem !important;}&#8221; el_class=&#8221;scrolll&#8221;][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589dc359\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/IC212000-27_IC3100-27_A2-LE23-27_LR4M-RAL_Sifon-27_iconico-2-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589dcc4c\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LE23-27_iconico_2-3-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1641830979111{margin-top: 1rem !important;}&#8221; el_class=&#8221;scrolll&#8221;][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589dd547\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LE22-64_iconico-4-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589dde89\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LP22-20_iconico_4-2-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589de7ec\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LP22-64_iconico_3-3-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1641830984192{margin-top: 1rem !important;}&#8221; el_class=&#8221;scrolll&#8221;][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589df006\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LP21-28_iconico-2.jpeg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589df88c\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LE22-20_iconico_3-3-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1641831005175{margin-top: 1rem !important;}&#8221; el_class=&#8221;scrolll&#8221;][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589e0119\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LE22-16_iconico-3.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589e0973\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LE212-20_iconico-2-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589e11d0\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LP22-20_iconico-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1641831030199{margin-top: 1rem !important;}&#8221; el_class=&#8221;scrolll&#8221;][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589e19fa\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A2-LE23-MP-64_CUBE550-64_iconico-2-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589e2284\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A2-LP22-64_V64-64_IC3430-63_D-SP3-64_14705002305-64_14560502002-64_iconico-4-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1641831034903{margin-top: 1rem !important;}&#8221; el_class=&#8221;scrolll&#8221;][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589e2a65\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LE23-64_iconico_3-1-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589e3248\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LP22-64_iconico_5-1-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589e3a2a\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LP22-20_iconico-1-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1641831040711{margin-top: 1rem !important;}&#8221; el_class=&#8221;scrolll&#8221;][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589e42a9\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LP22-64_cobre_iconico_4.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589e4bda\" class=\" et-hovercard \">\n\t\t\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1641831053439{margin-top: 1rem !important;}&#8221; el_class=&#8221;scrolll&#8221;][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589e53ec\" class=\" et-hovercard \">\n\t\t\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589e5c01\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LP21-65_iconico-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589e6408\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LE23-64_iconico_2.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1641831059527{margin-top: 1rem !important;}&#8221; el_class=&#8221;scrolll&#8221;][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589e6c21\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LE23-27_iconico-4.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589e74db\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/C3480-27_A-LP22-27_LC1S-27_negro_iconico-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1641831064328{margin-top: 1rem !important;}&#8221; el_class=&#8221;scrolll&#8221;][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589e7de4\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LE11_acabats_iconico-5-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589e8636\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LE22-27_iconico_2-3.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589e8da3\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LP22-27_negro_iconico-1-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1641831110832{margin-top: 1rem !important;}&#8221; el_class=&#8221;scrolll&#8221;][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589e9634\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LE23-27_iconico-5.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589e9e5a\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LE23-64_cobre_iconico-scaled.jpg\" target=\"_self\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1641831101264{margin-top: 1rem !important;}&#8221; el_class=&#8221;scrolll&#8221;][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589ea668\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/IC212000-20_A-LE23-20_CR4M-28_14705202304-40_Sifon-20_niquel_iconico-1.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589eaeb7\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A2-LP31-65_LR4M-28_Sifon-65_iconico-3-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]\t<div id=\"et-hovercard-6a572589eb701\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LP22-64_iconico_2.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1641831115431{margin-top: 1rem !important;}&#8221; el_class=&#8221;scrolll&#8221;][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589ebfa4\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LP22-20_iconico_3-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]\t<div id=\"et-hovercard-6a572589ec9c0\" class=\" et-hovercard \">\n\t\t<a class=\"et-hovercard-link\" href=\"http:\/\/iconico.es\/wp-content\/uploads\/A-LP22-27_negro_iconico-scaled.jpg\" target=\"_blank\">\t\t<div class=\"et-hovercard-front et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"et-hovercard-back et-hovercard-side\">\n\t\t\t<div class=\"et-hovercard-inner\">\n\t\t\t\t<figure class=\"et-pricing-icon\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t<h3 class=\"et-pricing-head\"><\/h3>\n\t\t\t\t<div class=\"et-pricing-content\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\t[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm&#8221;][vc_separator][vc_column_text css=&#8221;.vc_custom_1642517310755{margin-top: 3% !important;margin-bottom: 3% !important;}&#8221;]\n<h3 style=\"text-align: center;\">Inspiration<\/h3>\n[\/vc_column_text][vc_images_carousel images=&#8221;6253,6120,6116,6118,6126,6241,6230,6245,6266,6325,6339,6343,6425,6357,6361&#8243; img_size=&#8221;350&#215;400&#8243; hide_pagination_control=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1638293240991{margin-top: 2% !important;}&#8221;][vc_column][vc_btn title=&#8221;VIEW PRODUCTS&#8221; style=&#8221;outline&#8221; shape=&#8221;square&#8221; color=&#8221;black&#8221; align=&#8221;center&#8221; link=&#8221;url:https%3A%2F%2Ficonico.es%2Fproductos%2Fgriferia-de-lavabo-coleccion-a%2F&#8221; css=&#8221;.vc_custom_1663836809315{margin-top: 45px !important;margin-bottom: 45px !important;}&#8221;][\/vc_column][\/vc_row][vc_column][\/vc_column][vc_column][\/vc_column]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row et_column_align=&#8221;align-center&#8221; css=&#8221;.vc_custom_1644854299335{margin-top: 3% !important;}&#8221;][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text] Circles and cylinders are the essence of Collection A design. This basin faucets collection has a variety of models of different heights, spout lengths, installation possibilities, \u2014 wall-mounted or on countertop\u2014, mixer typologies to adapt to the functional and aesthetic requirements of each&hellip;<\/p>\n","protected":false},"author":12,"featured_media":0,"parent":37239,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-37244","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Collection A basin faucets - IC\u00d3NICO - Dise\u00f1os para la arquitectura<\/title>\r\n<meta name=\"description\" content=\"Basin, shower and bathtub faucets. Models with different heights, spout lengths and installation possibilities. Available in 7 finishes.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Collection A basin faucets - IC\u00d3NICO - Dise\u00f1os para la arquitectura\" \/>\r\n<meta property=\"og:description\" content=\"Basin, shower and bathtub faucets. Models with different heights, spout lengths and installation possibilities. Available in 7 finishes.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/\" \/>\r\n<meta property=\"og:site_name\" content=\"IC\u00d3NICO - Dise\u00f1os para la arquitectura\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/iconicospain\" \/>\r\n<meta property=\"article:modified_time\" content=\"2022-09-22T08:53:51+00:00\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/\",\"url\":\"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/\",\"name\":\"Collection A basin faucets - IC\u00d3NICO - Dise\u00f1os para la arquitectura\",\"isPartOf\":{\"@id\":\"https:\/\/iconico.es\/en\/#website\"},\"datePublished\":\"2022-08-04T07:25:51+00:00\",\"dateModified\":\"2022-09-22T08:53:51+00:00\",\"description\":\"Basin, shower and bathtub faucets. Models with different heights, spout lengths and installation possibilities. Available in 7 finishes.\",\"breadcrumb\":{\"@id\":\"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/iconico.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Product&#8217;s catalogue\",\"item\":\"https:\/\/iconico.es\/en\/catalogue\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Faucets\",\"item\":\"https:\/\/iconico.es\/en\/catalogue\/faucets\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Basin faucets\",\"item\":\"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Collection A basin faucets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/iconico.es\/en\/#website\",\"url\":\"https:\/\/iconico.es\/en\/\",\"name\":\"IC\u00d3NICO - Dise\u00f1os para la arquitectura\",\"description\":\"IC\u00d3NICO dise\u00f1a productos atemporales para la arquitectura que responden a los mismos criterios tanto en sus formas como en sus acabados, lujo y calidad.\",\"publisher\":{\"@id\":\"https:\/\/iconico.es\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/iconico.es\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/iconico.es\/en\/#organization\",\"name\":\"Dise\u00f1o Ic\u00f3nico, s.l.\",\"url\":\"https:\/\/iconico.es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/iconico.es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/iconico.es\/wp-content\/uploads\/2021\/09\/cropped-iconico_Logotipo.png\",\"contentUrl\":\"https:\/\/iconico.es\/wp-content\/uploads\/2021\/09\/cropped-iconico_Logotipo.png\",\"width\":322,\"height\":80,\"caption\":\"Dise\u00f1o Ic\u00f3nico, s.l.\"},\"image\":{\"@id\":\"https:\/\/iconico.es\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/iconicospain\",\"https:\/\/www.instagram.com\/iconico\/\",\"https:\/\/www.linkedin.com\/company\/iconico-elements-for-architecture\",\"https:\/\/www.pinterest.es\/iconico_es\/\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Collection A basin faucets - IC\u00d3NICO - Dise\u00f1os para la arquitectura","description":"Basin, shower and bathtub faucets. Models with different heights, spout lengths and installation possibilities. Available in 7 finishes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/","og_locale":"en_US","og_type":"article","og_title":"Collection A basin faucets - IC\u00d3NICO - Dise\u00f1os para la arquitectura","og_description":"Basin, shower and bathtub faucets. Models with different heights, spout lengths and installation possibilities. Available in 7 finishes.","og_url":"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/","og_site_name":"IC\u00d3NICO - Dise\u00f1os para la arquitectura","article_publisher":"https:\/\/www.facebook.com\/iconicospain","article_modified_time":"2022-09-22T08:53:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/","url":"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/","name":"Collection A basin faucets - IC\u00d3NICO - Dise\u00f1os para la arquitectura","isPartOf":{"@id":"https:\/\/iconico.es\/en\/#website"},"datePublished":"2022-08-04T07:25:51+00:00","dateModified":"2022-09-22T08:53:51+00:00","description":"Basin, shower and bathtub faucets. Models with different heights, spout lengths and installation possibilities. Available in 7 finishes.","breadcrumb":{"@id":"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/collection-a-basin-faucets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/iconico.es\/en\/"},{"@type":"ListItem","position":2,"name":"Product&#8217;s catalogue","item":"https:\/\/iconico.es\/en\/catalogue\/"},{"@type":"ListItem","position":3,"name":"Faucets","item":"https:\/\/iconico.es\/en\/catalogue\/faucets\/"},{"@type":"ListItem","position":4,"name":"Basin faucets","item":"https:\/\/iconico.es\/en\/catalogue\/faucets\/basin\/"},{"@type":"ListItem","position":5,"name":"Collection A basin faucets"}]},{"@type":"WebSite","@id":"https:\/\/iconico.es\/en\/#website","url":"https:\/\/iconico.es\/en\/","name":"IC\u00d3NICO - Dise\u00f1os para la arquitectura","description":"IC\u00d3NICO dise\u00f1a productos atemporales para la arquitectura que responden a los mismos criterios tanto en sus formas como en sus acabados, lujo y calidad.","publisher":{"@id":"https:\/\/iconico.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iconico.es\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/iconico.es\/en\/#organization","name":"Dise\u00f1o Ic\u00f3nico, s.l.","url":"https:\/\/iconico.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/iconico.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/iconico.es\/wp-content\/uploads\/2021\/09\/cropped-iconico_Logotipo.png","contentUrl":"https:\/\/iconico.es\/wp-content\/uploads\/2021\/09\/cropped-iconico_Logotipo.png","width":322,"height":80,"caption":"Dise\u00f1o Ic\u00f3nico, s.l."},"image":{"@id":"https:\/\/iconico.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iconicospain","https:\/\/www.instagram.com\/iconico\/","https:\/\/www.linkedin.com\/company\/iconico-elements-for-architecture","https:\/\/www.pinterest.es\/iconico_es\/"]}]}},"_links":{"self":[{"href":"https:\/\/iconico.es\/en\/wp-json\/wp\/v2\/pages\/37244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iconico.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iconico.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iconico.es\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/iconico.es\/en\/wp-json\/wp\/v2\/comments?post=37244"}],"version-history":[{"count":0,"href":"https:\/\/iconico.es\/en\/wp-json\/wp\/v2\/pages\/37244\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/iconico.es\/en\/wp-json\/wp\/v2\/pages\/37239"}],"wp:attachment":[{"href":"https:\/\/iconico.es\/en\/wp-json\/wp\/v2\/media?parent=37244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}